{"id":5927,"date":"2017-06-22T11:21:03","date_gmt":"2017-06-22T19:21:03","guid":{"rendered":"http:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png"},"modified":"2017-06-22T11:21:03","modified_gmt":"2017-06-22T19:21:03","slug":"mta-logo-2","status":"inherit","type":"attachment","link":"https:\/\/www.alaskastatefair.org\/site\/mta-logo-2\/","title":{"rendered":"MTA-logo"},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":""},"class_list":["post-5927","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MTA-logo - Alaska State Fair<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MTA-logo - Alaska State Fair\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png\" \/>\n<meta property=\"og:site_name\" content=\"Alaska State Fair\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alaskastatefair\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"119\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@alaskastatefair\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/MTA-logo.png\",\"url\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/MTA-logo.png\",\"name\":\"MTA-logo - Alaska State Fair\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/#website\"},\"datePublished\":\"2017-06-22T19:21:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/MTA-logo.png#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/MTA-logo.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/MTA-logo.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MTA-logo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/\",\"name\":\"Alaska State Fair\",\"description\":\"Welcome to the Alaska State Fair, home of an abundance of diverse vendors, food to please every palate, rides, concerts, acrobats, animals, exceptional educational exhibits, record-setting giant vegetables and beautiful flower gardens.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MTA-logo - Alaska State Fair","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png","og_locale":"en_US","og_type":"article","og_title":"MTA-logo - Alaska State Fair","og_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png","og_site_name":"Alaska State Fair","article_publisher":"https:\/\/www.facebook.com\/alaskastatefair\/","og_image":[{"width":185,"height":119,"url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@alaskastatefair","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png","url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png","name":"MTA-logo - Alaska State Fair","isPartOf":{"@id":"https:\/\/www.alaskastatefair.org\/site\/#website"},"datePublished":"2017-06-22T19:21:03+00:00","breadcrumb":{"@id":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alaskastatefair.org\/site\/"},{"@type":"ListItem","position":2,"name":"MTA-logo"}]},{"@type":"WebSite","@id":"https:\/\/www.alaskastatefair.org\/site\/#website","url":"https:\/\/www.alaskastatefair.org\/site\/","name":"Alaska State Fair","description":"Welcome to the Alaska State Fair, home of an abundance of diverse vendors, food to please every palate, rides, concerts, acrobats, animals, exceptional educational exhibits, record-setting giant vegetables and beautiful flower gardens.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alaskastatefair.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png'><img decoding=\"async\" width=\"185\" height=\"119\" src=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png 185w, https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo-184x119.png 184w\" sizes=\"(max-width: 185px) 100vw, 185px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":185,"height":119,"file":"2017\/06\/MTA-logo.png","sizes":{"thumbnail":{"file":"MTA-logo-150x119.png","width":150,"height":119,"mime_type":"image\/png","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo-150x119.png"},"et-recent-post-image":{"file":"MTA-logo-160x119.png","width":160,"height":119,"mime_type":"image\/png","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo-160x119.png"},"et-tabs-image-small":{"file":"MTA-logo-60x60.png","width":60,"height":60,"mime_type":"image\/png","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo-60x60.png"},"et-blog-page-thumb":{"file":"MTA-logo-184x119.png","width":184,"height":119,"mime_type":"image\/png","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo-184x119.png"},"et-portfolio-small-page-thumb":{"file":"MTA-logo-140x94.png","width":140,"height":94,"mime_type":"image\/png","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo-140x94.png"},"et-portfolio-small-portrait-page-thumb":{"file":"MTA-logo-140x119.png","width":140,"height":119,"mime_type":"image\/png","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo-140x119.png"},"full":{"file":"MTA-logo.png","width":185,"height":119,"mime_type":"image\/png","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/06\/MTA-logo.png","_links":{"self":[{"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/media\/5927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/comments?post=5927"}]}}