{"id":5149,"date":"2017-03-20T13:50:49","date_gmt":"2017-03-20T21:50:49","guid":{"rendered":"http:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg"},"modified":"2017-03-20T13:50:49","modified_gmt":"2017-03-20T21:50:49","slug":"souvenir-employees","status":"inherit","type":"attachment","link":"https:\/\/www.alaskastatefair.org\/site\/souvenir-employees\/","title":{"rendered":"Souvenir employees"},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":""},"class_list":["post-5149","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Souvenir employees - Alaska State Fair<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Souvenir employees - Alaska State Fair\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Alaska State Fair\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alaskastatefair\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1050\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@alaskastatefair\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Souvenir-employees.jpg\",\"url\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Souvenir-employees.jpg\",\"name\":\"Souvenir employees - Alaska State Fair\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/#website\"},\"datePublished\":\"2017-03-20T21:50:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Souvenir-employees.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Souvenir-employees.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Souvenir-employees.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Souvenir employees\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/\",\"name\":\"Alaska State Fair\",\"description\":\"Welcome to the Alaska State Fair, home of an abundance of diverse vendors, food to please every palate, rides, concerts, acrobats, animals, exceptional educational exhibits, record-setting giant vegetables and beautiful flower gardens.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Souvenir employees - Alaska State Fair","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg","og_locale":"en_US","og_type":"article","og_title":"Souvenir employees - Alaska State Fair","og_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg","og_site_name":"Alaska State Fair","article_publisher":"https:\/\/www.facebook.com\/alaskastatefair\/","og_image":[{"width":1050,"height":700,"url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@alaskastatefair","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg","url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg","name":"Souvenir employees - Alaska State Fair","isPartOf":{"@id":"https:\/\/www.alaskastatefair.org\/site\/#website"},"datePublished":"2017-03-20T21:50:49+00:00","breadcrumb":{"@id":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alaskastatefair.org\/site\/"},{"@type":"ListItem","position":2,"name":"Souvenir employees"}]},{"@type":"WebSite","@id":"https:\/\/www.alaskastatefair.org\/site\/#website","url":"https:\/\/www.alaskastatefair.org\/site\/","name":"Alaska State Fair","description":"Welcome to the Alaska State Fair, home of an abundance of diverse vendors, food to please every palate, rides, concerts, acrobats, animals, exceptional educational exhibits, record-setting giant vegetables and beautiful flower gardens.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alaskastatefair.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-300x200.jpg 300w, https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-768x512.jpg 768w, https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-1024x683.jpg 1024w, https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-321x214.jpg 321w, https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-140x94.jpg 140w, https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg 1050w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1050,"height":700,"file":"2017\/03\/Souvenir-employees.jpg","sizes":{"thumbnail":{"file":"Souvenir-employees-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-150x150.jpg"},"medium":{"file":"Souvenir-employees-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-300x200.jpg"},"medium_large":{"file":"Souvenir-employees-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-768x512.jpg"},"large":{"file":"Souvenir-employees-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-1024x683.jpg"},"et-featured-first":{"file":"Souvenir-employees-578x420.jpg","width":578,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-578x420.jpg"},"et-featured-second":{"file":"Souvenir-employees-578x208.jpg","width":578,"height":208,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-578x208.jpg"},"et-featured-category":{"file":"Souvenir-employees-578x280.jpg","width":578,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-578x280.jpg"},"et-featured-third":{"file":"Souvenir-employees-287x208.jpg","width":287,"height":208,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-287x208.jpg"},"et-recent-post-image":{"file":"Souvenir-employees-160x160.jpg","width":160,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-160x160.jpg"},"et-popular-post-image":{"file":"Souvenir-employees-319x160.jpg","width":319,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-319x160.jpg"},"et-popular-post-big-image":{"file":"Souvenir-employees-639x160.jpg","width":639,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-639x160.jpg"},"et-category-image":{"file":"Souvenir-employees-240x240.jpg","width":240,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-240x240.jpg"},"et-recent-first-image":{"file":"Souvenir-employees-321x214.jpg","width":321,"height":214,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-321x214.jpg"},"et-tabs-image-small":{"file":"Souvenir-employees-60x60.jpg","width":60,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-60x60.jpg"},"et-blog-page-thumb":{"file":"Souvenir-employees-184x184.jpg","width":184,"height":184,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-184x184.jpg"},"et-gallery-page-thumb":{"file":"Souvenir-employees-207x136.jpg","width":207,"height":136,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-207x136.jpg"},"et-portfolio-medium-page-thumb":{"file":"Souvenir-employees-260x170.jpg","width":260,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-260x170.jpg"},"et-portfolio-medium-portrait-page-thumb":{"file":"Souvenir-employees-260x315.jpg","width":260,"height":315,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-260x315.jpg"},"et-portfolio-small-page-thumb":{"file":"Souvenir-employees-140x94.jpg","width":140,"height":94,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-140x94.jpg"},"et-portfolio-small-portrait-page-thumb":{"file":"Souvenir-employees-140x170.jpg","width":140,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-140x170.jpg"},"et-portfolio-large-page-thumb":{"file":"Souvenir-employees-430x283.jpg","width":430,"height":283,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-430x283.jpg"},"et-portfolio-large-portrait-page-thumb":{"file":"Souvenir-employees-430x700.jpg","width":430,"height":700,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees-430x700.jpg"},"full":{"file":"Souvenir-employees.jpg","width":1050,"height":700,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"\u00a9 2012 Clark James Mishler","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Souvenir-employees.jpg","filename":"Souvenir-employees.jpg","filesize":256501,"_links":{"self":[{"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/media\/5149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/comments?post=5149"}]}}