{"id":5027,"date":"2017-03-20T13:39:07","date_gmt":"2017-03-20T21:39:07","guid":{"rendered":"http:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg"},"modified":"2017-03-20T13:39:07","modified_gmt":"2017-03-20T21:39:07","slug":"giant-vegatables-display","status":"inherit","type":"attachment","link":"https:\/\/www.alaskastatefair.org\/site\/giant-vegatables-display\/","title":{"rendered":"Giant vegatables display"},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":""},"class_list":["post-5027","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giant vegatables display - Alaska State Fair<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giant vegatables display - Alaska State Fair\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Alaska State Fair\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alaskastatefair\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@alaskastatefair\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Giant-vegatables-display.jpg\",\"url\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Giant-vegatables-display.jpg\",\"name\":\"Giant vegatables display - Alaska State Fair\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/#website\"},\"datePublished\":\"2017-03-20T21:39:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Giant-vegatables-display.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Giant-vegatables-display.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Giant-vegatables-display.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giant vegatables display\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/\",\"name\":\"Alaska State Fair\",\"description\":\"Welcome to the Alaska State Fair, home of an abundance of diverse vendors, food to please every palate, rides, concerts, acrobats, animals, exceptional educational exhibits, record-setting giant vegetables and beautiful flower gardens.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alaskastatefair.org\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giant vegatables display - Alaska State Fair","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg","og_locale":"en_US","og_type":"article","og_title":"Giant vegatables display - Alaska State Fair","og_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg","og_site_name":"Alaska State Fair","article_publisher":"https:\/\/www.facebook.com\/alaskastatefair\/","og_image":[{"width":700,"height":1050,"url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@alaskastatefair","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg","url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg","name":"Giant vegatables display - Alaska State Fair","isPartOf":{"@id":"https:\/\/www.alaskastatefair.org\/site\/#website"},"datePublished":"2017-03-20T21:39:07+00:00","breadcrumb":{"@id":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alaskastatefair.org\/site\/"},{"@type":"ListItem","position":2,"name":"Giant vegatables display"}]},{"@type":"WebSite","@id":"https:\/\/www.alaskastatefair.org\/site\/#website","url":"https:\/\/www.alaskastatefair.org\/site\/","name":"Alaska State Fair","description":"Welcome to the Alaska State Fair, home of an abundance of diverse vendors, food to please every palate, rides, concerts, acrobats, animals, exceptional educational exhibits, record-setting giant vegetables and beautiful flower gardens.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alaskastatefair.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-200x300.jpg 200w, https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-683x1024.jpg 683w, https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg 700w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":1050,"file":"2017\/03\/Giant-vegatables-display.jpg","sizes":{"thumbnail":{"file":"Giant-vegatables-display-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-150x150.jpg"},"medium":{"file":"Giant-vegatables-display-200x300.jpg","width":200,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-200x300.jpg"},"large":{"file":"Giant-vegatables-display-683x1024.jpg","width":683,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-683x1024.jpg"},"et-featured-first":{"file":"Giant-vegatables-display-578x420.jpg","width":578,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-578x420.jpg"},"et-featured-second":{"file":"Giant-vegatables-display-578x208.jpg","width":578,"height":208,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-578x208.jpg"},"et-featured-category":{"file":"Giant-vegatables-display-578x280.jpg","width":578,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-578x280.jpg"},"et-featured-third":{"file":"Giant-vegatables-display-287x208.jpg","width":287,"height":208,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-287x208.jpg"},"et-recent-post-image":{"file":"Giant-vegatables-display-160x160.jpg","width":160,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-160x160.jpg"},"et-popular-post-image":{"file":"Giant-vegatables-display-319x160.jpg","width":319,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-319x160.jpg"},"et-popular-post-big-image":{"file":"Giant-vegatables-display-639x160.jpg","width":639,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-639x160.jpg"},"et-category-image":{"file":"Giant-vegatables-display-240x240.jpg","width":240,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-240x240.jpg"},"et-recent-first-image":{"file":"Giant-vegatables-display-321x214.jpg","width":321,"height":214,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-321x214.jpg"},"et-tabs-image-small":{"file":"Giant-vegatables-display-60x60.jpg","width":60,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-60x60.jpg"},"et-blog-page-thumb":{"file":"Giant-vegatables-display-184x184.jpg","width":184,"height":184,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-184x184.jpg"},"et-gallery-page-thumb":{"file":"Giant-vegatables-display-207x136.jpg","width":207,"height":136,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-207x136.jpg"},"et-portfolio-medium-page-thumb":{"file":"Giant-vegatables-display-260x170.jpg","width":260,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-260x170.jpg"},"et-portfolio-medium-portrait-page-thumb":{"file":"Giant-vegatables-display-260x315.jpg","width":260,"height":315,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-260x315.jpg"},"et-portfolio-small-page-thumb":{"file":"Giant-vegatables-display-140x94.jpg","width":140,"height":94,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-140x94.jpg"},"et-portfolio-small-portrait-page-thumb":{"file":"Giant-vegatables-display-140x170.jpg","width":140,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-140x170.jpg"},"et-portfolio-large-page-thumb":{"file":"Giant-vegatables-display-430x283.jpg","width":430,"height":283,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-430x283.jpg"},"et-portfolio-large-portrait-page-thumb":{"file":"Giant-vegatables-display-430x860.jpg","width":430,"height":860,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display-430x860.jpg"},"full":{"file":"Giant-vegatables-display.jpg","width":700,"height":1050,"mime_type":"image\/jpeg","source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"\u00a9 2012 Clark James Mishler","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.alaskastatefair.org\/site\/wp-content\/uploads\/2017\/03\/Giant-vegatables-display.jpg","_links":{"self":[{"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/media\/5027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alaskastatefair.org\/site\/wp-json\/wp\/v2\/comments?post=5027"}]}}